{"id":5,"count":2,"description":"","link":"https:\/\/labprodigi.com\/centrevaldeloire\/ads\/pets\/","name":"Pets","slug":"pets","taxonomy":"listivo_14","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listivo_14\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listivo_14"}],"about":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/taxonomies\/listivo_14"}],"wp:post_type":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listings?listivo_14=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}