{"id":2932,"count":2,"description":"","link":"https:\/\/labprodigi.com\/centrevaldeloire\/ads\/collection\/","name":"Collection","slug":"collection","taxonomy":"listivo_14","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listivo_14\/2932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listivo_14"}],"about":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/taxonomies\/listivo_14"}],"wp:post_type":[{"href":"https:\/\/labprodigi.com\/centrevaldeloire\/wp-json\/wp\/v2\/listings?listivo_14=2932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}